{"id":16228,"date":"2016-05-10T12:41:32","date_gmt":"2016-05-10T12:41:32","guid":{"rendered":"https:\/\/ipo.org\/?p=16228"},"modified":"2016-05-13T12:43:28","modified_gmt":"2016-05-13T12:43:28","slug":"ipo-comments-proposed-draft-indonesian-patent-bill","status":"publish","type":"post","link":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/","title":{"rendered":"IPO Comments on Proposed Draft Indonesian Patent Bill"},"content":{"rendered":"<p><a href=\"https:\/\/ipo.org\/wp-content\/uploads\/2016\/05\/20160510-IPO-Comments-to-Indonesian-Draft-Patent-Bill.pdf\">IPO Comments on Proposed Draft Indonesian Patent Bill<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>IPO Comments on Proposed Draft Indonesian Patent Bill<\/p>\n","protected":false},"author":3376,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[67],"tags":[],"class_list":["post-16228","post","type-post","status-publish","format-standard","hentry","category-testimony-comments"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IPO Comments on Proposed Draft Indonesian Patent Bill - Intellectual Property Owners Association<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IPO Comments on Proposed Draft Indonesian Patent Bill - Intellectual Property Owners Association\" \/>\n<meta property=\"og:description\" content=\"IPO Comments on Proposed Draft Indonesian Patent Bill\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/\" \/>\n<meta property=\"og:site_name\" content=\"Intellectual Property Owners Association\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IPOAssociation\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T12:41:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-13T12:43:28+00:00\" \/>\n<meta name=\"author\" content=\"Robin Muthig\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ipo\" \/>\n<meta name=\"twitter:site\" content=\"@ipo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin Muthig\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/\"},\"author\":{\"name\":\"Robin Muthig\",\"@id\":\"https:\\\/\\\/ipo.org\\\/#\\\/schema\\\/person\\\/6c501283d223109424c9e8c88e2ae14e\"},\"headline\":\"IPO Comments on Proposed Draft Indonesian Patent Bill\",\"datePublished\":\"2016-05-10T12:41:32+00:00\",\"dateModified\":\"2016-05-13T12:43:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/\"},\"wordCount\":16,\"publisher\":{\"@id\":\"https:\\\/\\\/ipo.org\\\/#organization\"},\"articleSection\":[\"Testimony and Comments\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/\",\"url\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/\",\"name\":\"IPO Comments on Proposed Draft Indonesian Patent Bill - Intellectual Property Owners Association\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ipo.org\\\/#website\"},\"datePublished\":\"2016-05-10T12:41:32+00:00\",\"dateModified\":\"2016-05-13T12:43:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/ipo-comments-proposed-draft-indonesian-patent-bill\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ipo.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IPO Comments on Proposed Draft Indonesian Patent Bill\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ipo.org\\\/#website\",\"url\":\"https:\\\/\\\/ipo.org\\\/\",\"name\":\"Intellectual Property Owners Association\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ipo.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ipo.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ipo.org\\\/#organization\",\"name\":\"Intellectual Property Owners Association\",\"url\":\"https:\\\/\\\/ipo.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ipo.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ipo.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ipo_logo.png\",\"contentUrl\":\"https:\\\/\\\/ipo.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ipo_logo.png\",\"width\":570,\"height\":226,\"caption\":\"Intellectual Property Owners Association\"},\"image\":{\"@id\":\"https:\\\/\\\/ipo.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IPOAssociation\\\/\",\"https:\\\/\\\/x.com\\\/ipo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ipoassociation\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ipo.org\\\/#\\\/schema\\\/person\\\/6c501283d223109424c9e8c88e2ae14e\",\"name\":\"Robin Muthig\",\"description\":\"86569\",\"url\":\"https:\\\/\\\/ipo.org\\\/index.php\\\/author\\\/robin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IPO Comments on Proposed Draft Indonesian Patent Bill - Intellectual Property Owners Association","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/","og_locale":"en_US","og_type":"article","og_title":"IPO Comments on Proposed Draft Indonesian Patent Bill - Intellectual Property Owners Association","og_description":"IPO Comments on Proposed Draft Indonesian Patent Bill","og_url":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/","og_site_name":"Intellectual Property Owners Association","article_publisher":"https:\/\/www.facebook.com\/IPOAssociation\/","article_published_time":"2016-05-10T12:41:32+00:00","article_modified_time":"2016-05-13T12:43:28+00:00","author":"Robin Muthig","twitter_card":"summary_large_image","twitter_creator":"@ipo","twitter_site":"@ipo","twitter_misc":{"Written by":"Robin Muthig"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/#article","isPartOf":{"@id":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/"},"author":{"name":"Robin Muthig","@id":"https:\/\/ipo.org\/#\/schema\/person\/6c501283d223109424c9e8c88e2ae14e"},"headline":"IPO Comments on Proposed Draft Indonesian Patent Bill","datePublished":"2016-05-10T12:41:32+00:00","dateModified":"2016-05-13T12:43:28+00:00","mainEntityOfPage":{"@id":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/"},"wordCount":16,"publisher":{"@id":"https:\/\/ipo.org\/#organization"},"articleSection":["Testimony and Comments"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/","url":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/","name":"IPO Comments on Proposed Draft Indonesian Patent Bill - Intellectual Property Owners Association","isPartOf":{"@id":"https:\/\/ipo.org\/#website"},"datePublished":"2016-05-10T12:41:32+00:00","dateModified":"2016-05-13T12:43:28+00:00","breadcrumb":{"@id":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ipo.org\/index.php\/ipo-comments-proposed-draft-indonesian-patent-bill\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ipo.org\/"},{"@type":"ListItem","position":2,"name":"IPO Comments on Proposed Draft Indonesian Patent Bill"}]},{"@type":"WebSite","@id":"https:\/\/ipo.org\/#website","url":"https:\/\/ipo.org\/","name":"Intellectual Property Owners Association","description":"","publisher":{"@id":"https:\/\/ipo.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ipo.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ipo.org\/#organization","name":"Intellectual Property Owners Association","url":"https:\/\/ipo.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ipo.org\/#\/schema\/logo\/image\/","url":"https:\/\/ipo.org\/wp-content\/uploads\/2019\/06\/ipo_logo.png","contentUrl":"https:\/\/ipo.org\/wp-content\/uploads\/2019\/06\/ipo_logo.png","width":570,"height":226,"caption":"Intellectual Property Owners Association"},"image":{"@id":"https:\/\/ipo.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IPOAssociation\/","https:\/\/x.com\/ipo","https:\/\/www.linkedin.com\/company\/ipoassociation\/"]},{"@type":"Person","@id":"https:\/\/ipo.org\/#\/schema\/person\/6c501283d223109424c9e8c88e2ae14e","name":"Robin Muthig","description":"86569","url":"https:\/\/ipo.org\/index.php\/author\/robin\/"}]}},"_links":{"self":[{"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/posts\/16228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/users\/3376"}],"replies":[{"embeddable":true,"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/comments?post=16228"}],"version-history":[{"count":1,"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/posts\/16228\/revisions"}],"predecessor-version":[{"id":16230,"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/posts\/16228\/revisions\/16230"}],"wp:attachment":[{"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/media?parent=16228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/categories?post=16228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipo.org\/index.php\/wp-json\/wp\/v2\/tags?post=16228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}